{"id":8,"count":45,"description":"","link":"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/","name":"Open calls","slug":"open-calls","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/8\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/category\\\/open-calls\\\/#listItem\",\"name\":\"Open calls\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/category\\\/open-calls\\\/#listItem\",\"position\":2,\"name\":\"Open calls\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/8\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/8\\\/\",\"name\":\"Open calls | Feminine Moments\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/8\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Open calls | Feminine Moments","description":"","canonical_url":"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories\/8\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.femininemoments.dk\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/#listItem","name":"Open calls"}},{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/#listItem","position":2,"name":"Open calls","previousItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories\/8\/#collectionpage","url":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories\/8\/","name":"Open calls | Feminine Moments","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories\/8\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.femininemoments.dk\/blog\/#organization","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","url":"https:\/\/www.femininemoments.dk\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.femininemoments.dk\/blog\/#website","url":"https:\/\/www.femininemoments.dk\/blog\/","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.femininemoments.dk\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOpen calls\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.femininemoments.dk\/blog"},{"label":"Open calls","link":"https:\/\/www.femininemoments.dk\/blog\/category\/open-calls\/"}],"_links":{"self":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}