{"id":318,"count":1,"description":"","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/","name":"Nomy Lamm","slug":"nomy-lamm","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/318\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/nomy-lamm\\\/#listItem\",\"name\":\"Nomy Lamm\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/nomy-lamm\\\/#listItem\",\"position\":2,\"name\":\"Nomy Lamm\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/318\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/318\\\/\",\"name\":\"Nomy Lamm | Feminine Moments\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/318\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nomy Lamm | Feminine Moments","description":"","canonical_url":"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/318\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.femininemoments.dk\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/#listItem","name":"Nomy Lamm"}},{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/#listItem","position":2,"name":"Nomy Lamm","previousItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/318\/#collectionpage","url":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/318\/","name":"Nomy Lamm | Feminine Moments","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/318\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.femininemoments.dk\/blog\/#organization","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","url":"https:\/\/www.femininemoments.dk\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.femininemoments.dk\/blog\/#website","url":"https:\/\/www.femininemoments.dk\/blog\/","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.femininemoments.dk\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNomy Lamm\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.femininemoments.dk\/blog"},{"label":"Nomy Lamm","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/nomy-lamm\/"}],"_links":{"self":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/posts?tags=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}