{"id":578,"count":4,"description":"","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/","name":"Joan E. Biren","slug":"joan-e-biren","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/578\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/joan-e-biren\\\/#listItem\",\"name\":\"Joan E. Biren\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/joan-e-biren\\\/#listItem\",\"position\":2,\"name\":\"Joan E. Biren\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/578\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/578\\\/\",\"name\":\"Joan E. Biren | Feminine Moments\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/578\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Joan E. Biren | Feminine Moments","description":"","canonical_url":"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/578\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.femininemoments.dk\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/#listItem","name":"Joan E. Biren"}},{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/#listItem","position":2,"name":"Joan E. Biren","previousItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/578\/#collectionpage","url":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/578\/","name":"Joan E. Biren | Feminine Moments","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/578\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.femininemoments.dk\/blog\/#organization","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","url":"https:\/\/www.femininemoments.dk\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.femininemoments.dk\/blog\/#website","url":"https:\/\/www.femininemoments.dk\/blog\/","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.femininemoments.dk\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJoan E. Biren\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.femininemoments.dk\/blog"},{"label":"Joan E. Biren","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/joan-e-biren\/"}],"_links":{"self":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/posts?tags=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}