{"id":825,"count":1,"description":"","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/","name":"Angela Yukiko Shintani","slug":"angela-yukiko-shintani","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/825\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/angela-yukiko-shintani\\\/#listItem\",\"name\":\"Angela Yukiko Shintani\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/tag\\\/angela-yukiko-shintani\\\/#listItem\",\"position\":2,\"name\":\"Angela Yukiko Shintani\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/825\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/825\\\/\",\"name\":\"Angela Yukiko Shintani | Feminine Moments\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/825\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/\",\"name\":\"Feminine Moments\",\"description\":\"Queer Feminist Art Worldwide\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.femininemoments.dk\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Angela Yukiko Shintani | Feminine Moments","description":"","canonical_url":"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/825\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.femininemoments.dk\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/#listItem","name":"Angela Yukiko Shintani"}},{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/#listItem","position":2,"name":"Angela Yukiko Shintani","previousItem":{"@type":"ListItem","@id":"https:\/\/www.femininemoments.dk\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/825\/#collectionpage","url":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/825\/","name":"Angela Yukiko Shintani | Feminine Moments","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/825\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.femininemoments.dk\/blog\/#organization","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","url":"https:\/\/www.femininemoments.dk\/blog\/"},{"@type":"WebSite","@id":"https:\/\/www.femininemoments.dk\/blog\/#website","url":"https:\/\/www.femininemoments.dk\/blog\/","name":"Feminine Moments","description":"Queer Feminist Art Worldwide","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.femininemoments.dk\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.femininemoments.dk\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAngela Yukiko Shintani\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.femininemoments.dk\/blog"},{"label":"Angela Yukiko Shintani","link":"https:\/\/www.femininemoments.dk\/blog\/tag\/angela-yukiko-shintani\/"}],"_links":{"self":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.femininemoments.dk\/blog\/wp-json\/wp\/v2\/posts?tags=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}